{"id":86518,"date":"2025-12-15T14:23:11","date_gmt":"2025-12-15T13:23:11","guid":{"rendered":"https:\/\/www.valleedazergues.com\/?post_type=offres-individuels&#038;p=86518"},"modified":"2025-12-15T14:23:11","modified_gmt":"2025-12-15T13:23:11","slug":"noel-aux-chateaux","status":"publish","type":"offres-individuels","link":"https:\/\/www.valleedazergues.com\/en\/individual-offers\/noel-aux-chateaux\/","title":{"rendered":"No\u00ebl aux ch\u00e2teaux"},"author":2,"featured_media":86525,"template":"","class_list":["post-86518","offres-individuels","type-offres-individuels","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>No\u00ebl aux ch\u00e2teaux - Autocars de la Vall\u00e9e d&#039;Azergues<\/title>\n<meta name=\"description\" content=\"Int\u00e9rieur des ch\u00e2teaux joliment d\u00e9cor\u00e9s pour les f\u00eates de No\u00ebl : le ch\u00e2teau d\u2019Amboise avec une exposition autour des jouets, le ch\u00e2teau de Chenonceau avec une exposition autour des fleurs, le Logis Royal de Loches, sur les contes de no\u00ebl !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.valleedazergues.com\/en\/individual-offers\/noel-aux-chateaux\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"No\u00ebl aux ch\u00e2teaux - Autocars de la Vall\u00e9e d&#039;Azergues\" \/>\n<meta property=\"og:description\" content=\"Int\u00e9rieur des ch\u00e2teaux joliment d\u00e9cor\u00e9s pour les f\u00eates de No\u00ebl : le ch\u00e2teau d\u2019Amboise avec une exposition autour des jouets, le ch\u00e2teau de Chenonceau avec une exposition autour des fleurs, le Logis Royal de Loches, sur les contes de no\u00ebl !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.valleedazergues.com\/en\/individual-offers\/noel-aux-chateaux\/\" \/>\n<meta property=\"og:site_name\" content=\"Autocars de la Vall\u00e9e d&#039;Azergues\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/autocarsvalleedazergues\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.valleedazergues.com\/wp-content\/uploads\/2025\/12\/4_noel-au-chateau-de-chenonceau-edition-2019_jean-christophe-coutand_2030-12-31_high.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"2250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.valleedazergues.com\\\/en\\\/individual-offers\\\/noel-aux-chateaux\\\/\",\"url\":\"https:\\\/\\\/www.valleedazergues.com\\\/en\\\/individual-offers\\\/noel-aux-chateaux\\\/\",\"name\":\"No\u00ebl aux ch\u00e2teaux - Autocars de la Vall\u00e9e d&#039;Azergues\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valleedazergues.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.valleedazergues.com\\\/en\\\/individual-offers\\\/noel-aux-chateaux\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valleedazergues.com\\\/en\\\/individual-offers\\\/noel-aux-chateaux\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valleedazergues.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/4_noel-au-chateau-de-chenonceau-edition-2019_jean-christophe-coutand_2030-12-31_high.jpeg\",\"datePublished\":\"2025-12-15T13:23:11+00:00\",\"description\":\"Int\u00e9rieur des ch\u00e2teaux joliment d\u00e9cor\u00e9s pour les f\u00eates de No\u00ebl : le ch\u00e2teau d\u2019Amboise avec une exposition autour des jouets, le ch\u00e2teau de Chenonceau avec une exposition autour des fleurs, le Logis Royal de Loches, sur les contes de no\u00ebl !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.valleedazergues.com\\\/en\\\/individual-offers\\\/noel-aux-chateaux\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.valleedazergues.com\\\/en\\\/individual-offers\\\/noel-aux-chateaux\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.valleedazergues.com\\\/en\\\/individual-offers\\\/noel-aux-chateaux\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.valleedazergues.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/4_noel-au-chateau-de-chenonceau-edition-2019_jean-christophe-coutand_2030-12-31_high.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.valleedazergues.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/4_noel-au-chateau-de-chenonceau-edition-2019_jean-christophe-coutand_2030-12-31_high.jpeg\",\"width\":1800,\"height\":2250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.valleedazergues.com\\\/en\\\/individual-offers\\\/noel-aux-chateaux\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.valleedazergues.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Offres Individuels\",\"item\":\"https:\\\/\\\/www.valleedazergues.com\\\/en\\\/individual-offers\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"No\u00ebl aux ch\u00e2teaux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.valleedazergues.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.valleedazergues.com\\\/en\\\/\",\"name\":\"Autocars de la Vall\u00e9e d'Azergues\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.valleedazergues.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.valleedazergues.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.valleedazergues.com\\\/en\\\/#organization\",\"name\":\"Autocars Vall\u00e9e d'Azergues\",\"url\":\"https:\\\/\\\/www.valleedazergues.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.valleedazergues.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.valleedazergues.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/partage-site.jpg\",\"contentUrl\":\"https:\\\/\\\/www.valleedazergues.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/partage-site.jpg\",\"width\":560,\"height\":292,\"caption\":\"Autocars Vall\u00e9e d'Azergues\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valleedazergues.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/autocarsvalleedazergues\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"No\u00ebl aux ch\u00e2teaux - Autocars de la Vall\u00e9e d&#039;Azergues","description":"Int\u00e9rieur des ch\u00e2teaux joliment d\u00e9cor\u00e9s pour les f\u00eates de No\u00ebl : le ch\u00e2teau d\u2019Amboise avec une exposition autour des jouets, le ch\u00e2teau de Chenonceau avec une exposition autour des fleurs, le Logis Royal de Loches, sur les contes de no\u00ebl !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.valleedazergues.com\/en\/individual-offers\/noel-aux-chateaux\/","og_locale":"en_GB","og_type":"article","og_title":"No\u00ebl aux ch\u00e2teaux - Autocars de la Vall\u00e9e d&#039;Azergues","og_description":"Int\u00e9rieur des ch\u00e2teaux joliment d\u00e9cor\u00e9s pour les f\u00eates de No\u00ebl : le ch\u00e2teau d\u2019Amboise avec une exposition autour des jouets, le ch\u00e2teau de Chenonceau avec une exposition autour des fleurs, le Logis Royal de Loches, sur les contes de no\u00ebl !","og_url":"https:\/\/www.valleedazergues.com\/en\/individual-offers\/noel-aux-chateaux\/","og_site_name":"Autocars de la Vall\u00e9e d&#039;Azergues","article_publisher":"https:\/\/www.facebook.com\/autocarsvalleedazergues\/","og_image":[{"width":1800,"height":2250,"url":"https:\/\/www.valleedazergues.com\/wp-content\/uploads\/2025\/12\/4_noel-au-chateau-de-chenonceau-edition-2019_jean-christophe-coutand_2030-12-31_high.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.valleedazergues.com\/en\/individual-offers\/noel-aux-chateaux\/","url":"https:\/\/www.valleedazergues.com\/en\/individual-offers\/noel-aux-chateaux\/","name":"No\u00ebl aux ch\u00e2teaux - Autocars de la Vall\u00e9e d&#039;Azergues","isPartOf":{"@id":"https:\/\/www.valleedazergues.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.valleedazergues.com\/en\/individual-offers\/noel-aux-chateaux\/#primaryimage"},"image":{"@id":"https:\/\/www.valleedazergues.com\/en\/individual-offers\/noel-aux-chateaux\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valleedazergues.com\/wp-content\/uploads\/2025\/12\/4_noel-au-chateau-de-chenonceau-edition-2019_jean-christophe-coutand_2030-12-31_high.jpeg","datePublished":"2025-12-15T13:23:11+00:00","description":"Int\u00e9rieur des ch\u00e2teaux joliment d\u00e9cor\u00e9s pour les f\u00eates de No\u00ebl : le ch\u00e2teau d\u2019Amboise avec une exposition autour des jouets, le ch\u00e2teau de Chenonceau avec une exposition autour des fleurs, le Logis Royal de Loches, sur les contes de no\u00ebl !","breadcrumb":{"@id":"https:\/\/www.valleedazergues.com\/en\/individual-offers\/noel-aux-chateaux\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.valleedazergues.com\/en\/individual-offers\/noel-aux-chateaux\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.valleedazergues.com\/en\/individual-offers\/noel-aux-chateaux\/#primaryimage","url":"https:\/\/www.valleedazergues.com\/wp-content\/uploads\/2025\/12\/4_noel-au-chateau-de-chenonceau-edition-2019_jean-christophe-coutand_2030-12-31_high.jpeg","contentUrl":"https:\/\/www.valleedazergues.com\/wp-content\/uploads\/2025\/12\/4_noel-au-chateau-de-chenonceau-edition-2019_jean-christophe-coutand_2030-12-31_high.jpeg","width":1800,"height":2250},{"@type":"BreadcrumbList","@id":"https:\/\/www.valleedazergues.com\/en\/individual-offers\/noel-aux-chateaux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.valleedazergues.com\/en\/"},{"@type":"ListItem","position":2,"name":"Offres Individuels","item":"https:\/\/www.valleedazergues.com\/en\/individual-offers\/"},{"@type":"ListItem","position":3,"name":"No\u00ebl aux ch\u00e2teaux"}]},{"@type":"WebSite","@id":"https:\/\/www.valleedazergues.com\/en\/#website","url":"https:\/\/www.valleedazergues.com\/en\/","name":"Autocars de la Vall\u00e9e d'Azergues","description":"","publisher":{"@id":"https:\/\/www.valleedazergues.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.valleedazergues.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.valleedazergues.com\/en\/#organization","name":"Autocars Vall\u00e9e d'Azergues","url":"https:\/\/www.valleedazergues.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.valleedazergues.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.valleedazergues.com\/wp-content\/uploads\/2021\/08\/partage-site.jpg","contentUrl":"https:\/\/www.valleedazergues.com\/wp-content\/uploads\/2021\/08\/partage-site.jpg","width":560,"height":292,"caption":"Autocars Vall\u00e9e d'Azergues"},"image":{"@id":"https:\/\/www.valleedazergues.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/autocarsvalleedazergues\/"]}]}},"featured_img":"https:\/\/www.valleedazergues.com\/wp-content\/uploads\/2025\/12\/4_noel-au-chateau-de-chenonceau-edition-2019_jean-christophe-coutand_2030-12-31_high.jpeg","coauthors":[],"author_meta":{"author_link":"https:\/\/www.valleedazergues.com\/en\/author\/autocarsvda\/","display_name":"autocarsVDA"},"relative_dates":{"created":"Posted 7 months ago","modified":"Updated 7 months ago"},"absolute_dates":{"created":"Posted on 15 December 2025","modified":"Updated on 15 December 2025"},"absolute_dates_time":{"created":"Posted on 15 December 2025 14:23","modified":"Updated on 15 December 2025 14:23"},"featured_img_caption":"","tax_additional":[],"series_order":"","_links":{"self":[{"href":"https:\/\/www.valleedazergues.com\/en\/wp-json\/wp\/v2\/offres-individuels\/86518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.valleedazergues.com\/en\/wp-json\/wp\/v2\/offres-individuels"}],"about":[{"href":"https:\/\/www.valleedazergues.com\/en\/wp-json\/wp\/v2\/types\/offres-individuels"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.valleedazergues.com\/en\/wp-json\/wp\/v2\/media\/86525"}],"wp:attachment":[{"href":"https:\/\/www.valleedazergues.com\/en\/wp-json\/wp\/v2\/media?parent=86518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}